{"id":754,"date":"2019-12-19T09:13:43","date_gmt":"2019-12-19T09:13:43","guid":{"rendered":"https:\/\/www.encontravitoria.com.br\/sobre\/?p=754"},"modified":"2019-12-19T09:14:26","modified_gmt":"2019-12-19T09:14:26","slug":"parque-botanico-vale-vitoria","status":"publish","type":"post","link":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/","title":{"rendered":"Parque Bot\u00e2nico Vale Vit\u00f3ria"},"content":{"rendered":"<div class=\"23ed37709e053b55400ee1990aeffe41\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Inaugurado em maio de 2004, o <strong>Parque Bot\u00e2nico Vale Vit\u00f3ria<\/strong> fica no Complexo Industrial do Porto de Tubar\u00e3o, em Vit\u00f3ria, capital do Esp\u00edrito Santo. Distante 12 quil\u00f4metros do centro da cidade, o Parque est\u00e1 localizado dentro do Cintur\u00e3o Verde da Vale e revela o processo de restaura\u00e7\u00e3o florestal e preserva\u00e7\u00e3o da Mata Atl\u00e2ntica.<\/p>\n<p>S\u00e3o 33 hectares de vegeta\u00e7\u00e3o voltados para a preserva\u00e7\u00e3o cultural e biol\u00f3gica da regi\u00e3o. Abertos \u00e0 visita\u00e7\u00e3o e ao lazer dos moradores e visitantes da cidade, estabelecem a integra\u00e7\u00e3o entre a comunidade e a Vale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-755 size-full\" title=\"Parque Bot\u00e2nico Vale Vit\u00f3ria\" src=\"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif\" alt=\"Parque Bot\u00e2nico Vale Vit\u00f3ria\" width=\"680\" height=\"189\" \/><\/p>\n<p>Sua localiza\u00e7\u00e3o foi estrategicamente escolhida para permitir o acesso do p\u00fablico sem interferir com as rotinas operacionais que a Vale desenvolve na \u00e1rea.<\/p>\n<h2>O Parque<\/h2>\n<p>Mais de 140 esp\u00e9cies de \u00e1rvores comp\u00f5em a flora diversificada do Parque Bot\u00e2nico Vale, com destaque para o pau-brasil, jacarand\u00e1 e ip\u00ea. Sua fauna silvestre apresenta esp\u00e9cies como caticoco, gamb\u00e1s, saguis e diversas esp\u00e9cies de aves que podem ser vistas em cinco trilhas ecol\u00f3gicas monitoradas. O parque conta tamb\u00e9m com um orquid\u00e1rio com cerca de 450 mudas, de 150 esp\u00e9cies nacionais e internacionais em sua estufa.<\/p>\n<h3>Parque Bot\u00e2nico Vale Vit\u00f3ria Jardim Sensorial<\/h3>\n<p>O Jardim Sensorial do Parque Bot\u00e2nico da Vale \u00e9 o primeiro da cidade de Vit\u00f3ria. E seu objetivo \u00e9 proporcionar um verdadeiro encontro com o meio ambiente e a descoberta de sensa\u00e7\u00f5es. Sua estrutura, com cerca de 100 metros quadrados, proporciona aos visitantes a oportunidade de explorar a natureza em um circuito que estimula os cinco sentidos humanos. Para sensibilizar o tato, pode-se tocar nas plantas e flores, sentindo as diferen\u00e7as entre textura e tamanho. Em rela\u00e7\u00e3o ao olfato, por exemplo, a percep\u00e7\u00e3o dos aromas \u00e9 desenvolvida em canteiros de ervas arom\u00e1ticas, plantas medicinais e flores. Quanto ao paladar, o visitante pode experimentar hortali\u00e7as, muitas vezes usadas como tempero na culin\u00e1ria tradicional. A audi\u00e7\u00e3o \u00e9 estimulada por uma cascata de pedras, ru\u00eddos t\u00edpicos da floresta e pelo sistema de som do jardim, que reproduz o canto de p\u00e1ssaros.<\/p>\n<p>Para poder atender o p\u00fablico em geral, os orientadores do Parque Bot\u00e2nico Vale tamb\u00e9m receberam treinamento em libras, a linguagem dos sinais utilizada por pessoas com defici\u00eancia auditiva.<\/p>\n<h3>Parque Bot\u00e2nico Vale Vit\u00f3ria Vag\u00e3o do Conhecimento<\/h3>\n<p>No dia 06\/05\/2011 foi inaugurado o Vag\u00e3o do Conhecimento, carro de passageiros com 18 metros de comprimento totalmente adaptado para receber 3,5 mil livros e 500 audiolivros (obras liter\u00e1rias compiladas em CDs), al\u00e9m de computadores conectados \u00e0 internet.\u00a0Instalado sobre trilhos ferrovi\u00e1rios na entrada do Parque, o Vag\u00e3o \u00e9 o primeiro espa\u00e7o do Esp\u00edrito Santo a abrigar uma audioteca. A proposta, com esse acervo, \u00e9 promover o acesso \u00e0 informa\u00e7\u00e3o a pessoas com defici\u00eancia visual que n\u00e3o tenham conhecimento do Braille. A \u201cbiblioteca sobre trilhos\u201d tamb\u00e9m possui mesas adaptadas e rampa de acesso para cadeirantes.<\/p>\n<p>O Vag\u00e3o do Conhecimento fica aberto ao p\u00fablico, gratuitamente, de ter\u00e7a a domingo, das 8h \u00e0s 17h. N\u00e3o \u00e9 necess\u00e1rio agendamento pr\u00e9vio para pesquisar o acervo da biblioteca.\u00a0Parte dos livros reunidos no Vag\u00e3o do Conhecimento foi reunida com a colabora\u00e7\u00e3o dos empregados Vale do Complexo de Tubar\u00e3o. Em uma campanha que durou 20 dias, eles doaram 1521 exemplares, de cl\u00e1ssicos da literatura a exemplares sobre bot\u00e2nica e hist\u00f3ria do Brasil.<\/p>\n<h3>Parque Bot\u00e2nico Vale Vit\u00f3ria Visita\u00e7\u00e3o<\/h3>\n<p>O Parque oferece diversas atra\u00e7\u00f5es aos visitantes, como trilhas ecol\u00f3gicas guiadas, visita ao Complexo de Tubar\u00e3o, parque de divers\u00e3o infantil ecologicamente correto e uma programa\u00e7\u00e3o de exposi\u00e7\u00f5es tem\u00e1ticas. Possui uma infra-estrutura para eventos com anfiteatro, salas de aula para mini-cursos, estacionamento e m\u00f3dulos com informa\u00e7\u00f5es sobre educa\u00e7\u00e3o ambiental que retratam temas como o bioma do Esp\u00edrito Santo e o ciclo do min\u00e9rio de ferro.<\/p>\n<p>A Vale abre as portas para a comunidade proporcionando aos visitantes conhecerem o seu processo produtivo, a sua hist\u00f3ria, os cuidados ambientais desenvolvidos atrav\u00e9s da realiza\u00e7\u00e3o do circuito dentro do Complexo de Tubar\u00e3o com \u00f4nibus.\u00a0Mensalmente, o parque tamb\u00e9m oferece aos visitantes e estudantes uma programa\u00e7\u00e3o diversificada que busca trabalhar a educa\u00e7\u00e3o ambiental, e difundir a cultura regional.<\/p>\n<h3>Vagas Parque Bot\u00e2nico Vale Vit\u00f3ria &#8211; Trabalhe Conosco<\/h3>\n<p>O Parque Bot\u00e2nico Vale Vit\u00f3ria disponibiliza vagas de trabalho durante todo ano. Para se informar sobre os processos seletivos e se candidatar as vagas acompanhe o site da empresa, onde \u00e9 poss\u00edvel se informar sobre vagas abertas, sal\u00e1rios e compet\u00eancias necess\u00e1rias para se candidatar ao processo.<\/p>\n<h3>Hor\u00e1rio de Funcionamento Parque Bot\u00e2nico Vale em Vit\u00f3ria<\/h3>\n<ul>\n<li>Ter\u00e7a a Domingo das 08h \u00e0s 17h<\/li>\n<\/ul>\n<h3>Onde fica, Endere\u00e7o e Telefone Parque Bot\u00e2nico Vale em Vit\u00f3ria<\/h3>\n<ul>\n<li>Av. dos Expedicion\u00e1rios, s\/n &#8211; Jardim Camburi &#8211; Vit\u00f3ria &#8211; ES<\/li>\n<li>Telefone: (27) 3333-6200<\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d14972.062059597945!2d-40.2601612!3d-20.2581913!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00xa6cb675203cd8d3a!2sParqueBotnicoVale!5e0!3m2!1spt-BR!2sbr!4v1576746152903!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"https:\/\/www.encontravitoria.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Inaugurado em maio de 2004, o Parque Bot\u00e2nico Vale Vit\u00f3ria fica no Complexo Industrial do Porto de Tubar\u00e3o, em Vit\u00f3ria, capital do Esp\u00edrito Santo. Distante 12 quil\u00f4metros do centro da cidade, o Parque est\u00e1 localizado dentro do Cintur\u00e3o Verde da Vale e revela o processo de restaura\u00e7\u00e3o florestal e preserva\u00e7\u00e3o da Mata Atl\u00e2ntica. S\u00e3o 33 hectares de vegeta\u00e7\u00e3o voltados para a preserva\u00e7\u00e3o cultural e biol\u00f3gica da regi\u00e3o. Abertos \u00e0 visita\u00e7\u00e3o e ao lazer dos moradores e visitantes da cidade, estabelecem a integra\u00e7\u00e3o entre a comunidade e a Vale. Sua localiza\u00e7\u00e3o foi estrategicamente escolhida para permitir o acesso do p\u00fablico sem <\/p>\n","protected":false},"author":1,"featured_media":755,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-em-vitoria","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Vit\u00f3ria\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-19T09:13:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-19T09:14:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Vit\u00f3ria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Vit\u00f3ria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/\"},\"author\":{\"name\":\"Encontra Vit\u00f3ria\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0f8e5bcc88fbadf1bad57afd504f48a2\"},\"headline\":\"Parque Bot\u00e2nico Vale Vit\u00f3ria\",\"datePublished\":\"2019-12-19T09:13:43+00:00\",\"dateModified\":\"2019-12-19T09:14:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/\"},\"wordCount\":910,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/parque-botanico-vale.gif\",\"articleSection\":[\"Lugares em Vit\u00f3ria\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/\",\"url\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/\",\"name\":\"Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/parque-botanico-vale.gif\",\"datePublished\":\"2019-12-19T09:13:43+00:00\",\"dateModified\":\"2019-12-19T09:14:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0f8e5bcc88fbadf1bad57afd504f48a2\"},\"description\":\"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/parque-botanico-vale.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/parque-botanico-vale.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/parque-botanico-vale-vitoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parque Bot\u00e2nico Vale Vit\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/\",\"name\":\"Encontra Vit\u00f3ria\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade Vit\u00f3ria e regi\u00e3o.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0f8e5bcc88fbadf1bad57afd504f48a2\",\"name\":\"Encontra Vit\u00f3ria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Vit\u00f3ria\"},\"sameAs\":[\"http:\\\/\\\/www.encontravitoria.com.br\"],\"url\":\"https:\\\/\\\/www.encontravitoria.com.br\\\/sobre\\\/author\\\/evitoria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o","description":"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/","og_locale":"pt_BR","og_type":"article","og_title":"Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o","og_description":"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/","og_site_name":"Encontra Vit\u00f3ria","article_published_time":"2019-12-19T09:13:43+00:00","article_modified_time":"2019-12-19T09:14:26+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif","type":"image\/gif"}],"author":"Encontra Vit\u00f3ria","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Vit\u00f3ria","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#article","isPartOf":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/"},"author":{"name":"Encontra Vit\u00f3ria","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/#\/schema\/person\/0f8e5bcc88fbadf1bad57afd504f48a2"},"headline":"Parque Bot\u00e2nico Vale Vit\u00f3ria","datePublished":"2019-12-19T09:13:43+00:00","dateModified":"2019-12-19T09:14:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/"},"wordCount":910,"commentCount":0,"image":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif","articleSection":["Lugares em Vit\u00f3ria"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/","url":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/","name":"Parque Bot\u00e2nico Vale Vit\u00f3ria: Parque, Jardim Sensorial, Visita\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#primaryimage"},"image":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif","datePublished":"2019-12-19T09:13:43+00:00","dateModified":"2019-12-19T09:14:26+00:00","author":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/#\/schema\/person\/0f8e5bcc88fbadf1bad57afd504f48a2"},"description":"Veja sobre o ( Parque Bot\u00e2nico Vale em Vit\u00f3ria ) - Informa\u00e7\u00f5es, parque, jardim sensorial, visita\u00e7\u00e3o, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#primaryimage","url":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif","contentUrl":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-content\/uploads\/2019\/12\/parque-botanico-vale.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/parque-botanico-vale-vitoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontravitoria.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Parque Bot\u00e2nico Vale Vit\u00f3ria"}]},{"@type":"WebSite","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/#website","url":"https:\/\/www.encontravitoria.com.br\/sobre\/","name":"Encontra Vit\u00f3ria","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade Vit\u00f3ria e regi\u00e3o.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontravitoria.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontravitoria.com.br\/sobre\/#\/schema\/person\/0f8e5bcc88fbadf1bad57afd504f48a2","name":"Encontra Vit\u00f3ria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Vit\u00f3ria"},"sameAs":["http:\/\/www.encontravitoria.com.br"],"url":"https:\/\/www.encontravitoria.com.br\/sobre\/author\/evitoria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/posts\/754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=754"}],"version-history":[{"count":0,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/posts\/754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/media\/755"}],"wp:attachment":[{"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontravitoria.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}